{"id":6825,"count":3,"description":"","link":"https:\/\/blogs.bmj.com\/tc\/category\/trade\/","name":"trade","slug":"trade","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>trade Archives - Blog - Tobacco Control<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bmj.com\/tc\/category\/trade\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"trade Archives - Blog - Tobacco Control\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bmj.com\/tc\/category\/trade\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Tobacco Control\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/category\\\/trade\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/category\\\/trade\\\/\",\"name\":\"trade Archives - Blog - Tobacco Control\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/category\\\/trade\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/category\\\/trade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"trade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/\",\"name\":\"Blog - Tobacco Control\",\"description\":\"A space to discuss the wider issues of tobacco control beyond the journal.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/#organization\",\"name\":\"Blog - Tobacco Control\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/files\\\/2017\\\/10\\\/blog-logo-tobacco-control.png\",\"contentUrl\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/files\\\/2017\\\/10\\\/blog-logo-tobacco-control.png\",\"width\":255,\"height\":34,\"caption\":\"Blog - Tobacco Control\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/tc\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"trade Archives - Blog - Tobacco Control","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bmj.com\/tc\/category\/trade\/","og_locale":"en_US","og_type":"article","og_title":"trade Archives - Blog - Tobacco Control","og_url":"https:\/\/blogs.bmj.com\/tc\/category\/trade\/","og_site_name":"Blog - Tobacco Control","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.bmj.com\/tc\/category\/trade\/","url":"https:\/\/blogs.bmj.com\/tc\/category\/trade\/","name":"trade Archives - Blog - Tobacco Control","isPartOf":{"@id":"https:\/\/blogs.bmj.com\/tc\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.bmj.com\/tc\/category\/trade\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bmj.com\/tc\/category\/trade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bmj.com\/tc\/"},{"@type":"ListItem","position":2,"name":"trade"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bmj.com\/tc\/#website","url":"https:\/\/blogs.bmj.com\/tc\/","name":"Blog - Tobacco Control","description":"A space to discuss the wider issues of tobacco control beyond the journal.","publisher":{"@id":"https:\/\/blogs.bmj.com\/tc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bmj.com\/tc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blogs.bmj.com\/tc\/#organization","name":"Blog - Tobacco Control","url":"https:\/\/blogs.bmj.com\/tc\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bmj.com\/tc\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.bmj.com\/tc\/files\/2017\/10\/blog-logo-tobacco-control.png","contentUrl":"https:\/\/blogs.bmj.com\/tc\/files\/2017\/10\/blog-logo-tobacco-control.png","width":255,"height":34,"caption":"Blog - Tobacco Control"},"image":{"@id":"https:\/\/blogs.bmj.com\/tc\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.bmj.com\/tc\/wp-json\/wp\/v2\/categories\/6825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bmj.com\/tc\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.bmj.com\/tc\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.bmj.com\/tc\/wp-json\/wp\/v2\/posts?categories=6825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}