{"id":304,"count":1,"description":"","link":"https:\/\/blogs.bmj.com\/medical-ethics\/tag\/public-health\/","name":"Public Health","slug":"public-health","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Public Health Archives - Journal of Medical Ethics blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bmj.com\/medical-ethics\/category\/public-health\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Public Health Archives - Journal of Medical Ethics blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bmj.com\/medical-ethics\/category\/public-health\/\" \/>\n<meta property=\"og:site_name\" content=\"Journal of Medical Ethics blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/category\\\/public-health\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/category\\\/public-health\\\/\",\"name\":\"Public Health Archives - Journal of Medical Ethics blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/category\\\/public-health\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/category\\\/public-health\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Public Health\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/\",\"name\":\"Journal of Medical Ethics blog\",\"description\":\"A blog to discuss the ethics of medicine in its many guises and formats.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/#organization\",\"name\":\"Journal of Medical Ethics blog\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/files\\\/2026\\\/04\\\/jme-logo.png\",\"contentUrl\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/files\\\/2026\\\/04\\\/jme-logo.png\",\"width\":200,\"height\":50,\"caption\":\"Journal of Medical Ethics blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/medical-ethics\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Public Health Archives - Journal of Medical Ethics blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bmj.com\/medical-ethics\/category\/public-health\/","og_locale":"en_US","og_type":"article","og_title":"Public Health Archives - Journal of Medical Ethics blog","og_url":"https:\/\/blogs.bmj.com\/medical-ethics\/category\/public-health\/","og_site_name":"Journal of Medical Ethics blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.bmj.com\/medical-ethics\/category\/public-health\/","url":"https:\/\/blogs.bmj.com\/medical-ethics\/category\/public-health\/","name":"Public Health Archives - Journal of Medical Ethics blog","isPartOf":{"@id":"https:\/\/blogs.bmj.com\/medical-ethics\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.bmj.com\/medical-ethics\/category\/public-health\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bmj.com\/medical-ethics\/category\/public-health\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bmj.com\/medical-ethics\/"},{"@type":"ListItem","position":2,"name":"Public Health"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bmj.com\/medical-ethics\/#website","url":"https:\/\/blogs.bmj.com\/medical-ethics\/","name":"Journal of Medical Ethics blog","description":"A blog to discuss the ethics of medicine in its many guises and formats.","publisher":{"@id":"https:\/\/blogs.bmj.com\/medical-ethics\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bmj.com\/medical-ethics\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blogs.bmj.com\/medical-ethics\/#organization","name":"Journal of Medical Ethics blog","url":"https:\/\/blogs.bmj.com\/medical-ethics\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bmj.com\/medical-ethics\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.bmj.com\/medical-ethics\/files\/2026\/04\/jme-logo.png","contentUrl":"https:\/\/blogs.bmj.com\/medical-ethics\/files\/2026\/04\/jme-logo.png","width":200,"height":50,"caption":"Journal of Medical Ethics blog"},"image":{"@id":"https:\/\/blogs.bmj.com\/medical-ethics\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.bmj.com\/medical-ethics\/wp-json\/wp\/v2\/tags\/304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bmj.com\/medical-ethics\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.bmj.com\/medical-ethics\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.bmj.com\/medical-ethics\/wp-json\/wp\/v2\/posts?tags=304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}