{"id":383,"name":"caitlinalder","url":"","description":"","link":"https:\/\/blogs.bmj.com\/injury-prevention\/author\/caitlinalder\/","slug":"caitlinalder","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8f7317efa0a11c9a723a66b41190b8f696bed04a8255a6262e9168fdd35acd6c?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8f7317efa0a11c9a723a66b41190b8f696bed04a8255a6262e9168fdd35acd6c?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8f7317efa0a11c9a723a66b41190b8f696bed04a8255a6262e9168fdd35acd6c?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>caitlinalder, Author at Injury Prevention: Editor&#039;s Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bmj.com\/injury-prevention\/author\/caitlinalder\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"caitlinalder, Author at Injury Prevention: Editor&#039;s Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bmj.com\/injury-prevention\/author\/caitlinalder\/\" \/>\n<meta property=\"og:site_name\" content=\"Injury Prevention: Editor&#039;s Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/0e9e49250c2c2b30c5d0c59318cf2966?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/author\\\/caitlinalder\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/author\\\/caitlinalder\\\/\",\"name\":\"caitlinalder, Author at Injury Prevention: Editor&#039;s Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/author\\\/caitlinalder\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/author\\\/caitlinalder\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/author\\\/caitlinalder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for caitlinalder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/\",\"name\":\"Injury Prevention: Editor&#039;s Blog\",\"description\":\"The official blog for the journal Injury Prevention.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#organization\",\"name\":\"Injury Prevention: Editor&#039;s Blog\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/files\\\/2017\\\/10\\\/blog-logo-injury-prevention.png\",\"contentUrl\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/files\\\/2017\\\/10\\\/blog-logo-injury-prevention.png\",\"width\":270,\"height\":34,\"caption\":\"Injury Prevention: Editor&#039;s Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#\\\/schema\\\/person\\\/6a90f3ceca251b386830821ec8125be0\",\"name\":\"caitlinalder\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f7317efa0a11c9a723a66b41190b8f696bed04a8255a6262e9168fdd35acd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f7317efa0a11c9a723a66b41190b8f696bed04a8255a6262e9168fdd35acd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f7317efa0a11c9a723a66b41190b8f696bed04a8255a6262e9168fdd35acd6c?s=96&d=mm&r=g\",\"caption\":\"caitlinalder\"},\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/author\\\/caitlinalder\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"caitlinalder, Author at Injury Prevention: Editor&#039;s Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bmj.com\/injury-prevention\/author\/caitlinalder\/","og_locale":"en_US","og_type":"profile","og_title":"caitlinalder, Author at Injury Prevention: Editor&#039;s Blog","og_url":"https:\/\/blogs.bmj.com\/injury-prevention\/author\/caitlinalder\/","og_site_name":"Injury Prevention: Editor&#039;s Blog","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/0e9e49250c2c2b30c5d0c59318cf2966?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/blogs.bmj.com\/injury-prevention\/author\/caitlinalder\/","url":"https:\/\/blogs.bmj.com\/injury-prevention\/author\/caitlinalder\/","name":"caitlinalder, Author at Injury Prevention: Editor&#039;s Blog","isPartOf":{"@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.bmj.com\/injury-prevention\/author\/caitlinalder\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.bmj.com\/injury-prevention\/author\/caitlinalder\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bmj.com\/injury-prevention\/author\/caitlinalder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bmj.com\/injury-prevention\/"},{"@type":"ListItem","position":2,"name":"Archives for caitlinalder"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#website","url":"https:\/\/blogs.bmj.com\/injury-prevention\/","name":"Injury Prevention: Editor&#039;s Blog","description":"The official blog for the journal Injury Prevention.","publisher":{"@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bmj.com\/injury-prevention\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#organization","name":"Injury Prevention: Editor&#039;s Blog","url":"https:\/\/blogs.bmj.com\/injury-prevention\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.bmj.com\/injury-prevention\/files\/2017\/10\/blog-logo-injury-prevention.png","contentUrl":"https:\/\/blogs.bmj.com\/injury-prevention\/files\/2017\/10\/blog-logo-injury-prevention.png","width":270,"height":34,"caption":"Injury Prevention: Editor&#039;s Blog"},"image":{"@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#\/schema\/person\/6a90f3ceca251b386830821ec8125be0","name":"caitlinalder","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8f7317efa0a11c9a723a66b41190b8f696bed04a8255a6262e9168fdd35acd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8f7317efa0a11c9a723a66b41190b8f696bed04a8255a6262e9168fdd35acd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8f7317efa0a11c9a723a66b41190b8f696bed04a8255a6262e9168fdd35acd6c?s=96&d=mm&r=g","caption":"caitlinalder"},"mainEntityOfPage":{"@id":"https:\/\/blogs.bmj.com\/injury-prevention\/author\/caitlinalder\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.bmj.com\/injury-prevention\/wp-json\/wp\/v2\/users\/383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bmj.com\/injury-prevention\/wp-json\/wp\/v2\/users"}]}}