{"id":13401,"count":1,"description":"","link":"https:\/\/blogs.bmj.com\/injury-prevention\/tag\/global-burden\/","name":"global burden","slug":"global-burden","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>global burden Archives - Injury Prevention: Editor&#039;s Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bmj.com\/injury-prevention\/tag\/global-burden\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"global burden Archives - Injury Prevention: Editor&#039;s Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bmj.com\/injury-prevention\/tag\/global-burden\/\" \/>\n<meta property=\"og:site_name\" content=\"Injury Prevention: Editor&#039;s Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/tag\\\/global-burden\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/tag\\\/global-burden\\\/\",\"name\":\"global burden Archives - Injury Prevention: Editor&#039;s Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/tag\\\/global-burden\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/tag\\\/global-burden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"global burden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/\",\"name\":\"Injury Prevention: Editor&#039;s Blog\",\"description\":\"The official blog for the journal Injury Prevention.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#organization\",\"name\":\"Injury Prevention: Editor&#039;s Blog\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/files\\\/2017\\\/10\\\/blog-logo-injury-prevention.png\",\"contentUrl\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/files\\\/2017\\\/10\\\/blog-logo-injury-prevention.png\",\"width\":270,\"height\":34,\"caption\":\"Injury Prevention: Editor&#039;s Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/injury-prevention\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"global burden Archives - Injury Prevention: Editor&#039;s Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bmj.com\/injury-prevention\/tag\/global-burden\/","og_locale":"en_US","og_type":"article","og_title":"global burden Archives - Injury Prevention: Editor&#039;s Blog","og_url":"https:\/\/blogs.bmj.com\/injury-prevention\/tag\/global-burden\/","og_site_name":"Injury Prevention: Editor&#039;s Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.bmj.com\/injury-prevention\/tag\/global-burden\/","url":"https:\/\/blogs.bmj.com\/injury-prevention\/tag\/global-burden\/","name":"global burden Archives - Injury Prevention: Editor&#039;s Blog","isPartOf":{"@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.bmj.com\/injury-prevention\/tag\/global-burden\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bmj.com\/injury-prevention\/tag\/global-burden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bmj.com\/injury-prevention\/"},{"@type":"ListItem","position":2,"name":"global burden"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#website","url":"https:\/\/blogs.bmj.com\/injury-prevention\/","name":"Injury Prevention: Editor&#039;s Blog","description":"The official blog for the journal Injury Prevention.","publisher":{"@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bmj.com\/injury-prevention\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#organization","name":"Injury Prevention: Editor&#039;s Blog","url":"https:\/\/blogs.bmj.com\/injury-prevention\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.bmj.com\/injury-prevention\/files\/2017\/10\/blog-logo-injury-prevention.png","contentUrl":"https:\/\/blogs.bmj.com\/injury-prevention\/files\/2017\/10\/blog-logo-injury-prevention.png","width":270,"height":34,"caption":"Injury Prevention: Editor&#039;s Blog"},"image":{"@id":"https:\/\/blogs.bmj.com\/injury-prevention\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.bmj.com\/injury-prevention\/wp-json\/wp\/v2\/tags\/13401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bmj.com\/injury-prevention\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.bmj.com\/injury-prevention\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.bmj.com\/injury-prevention\/wp-json\/wp\/v2\/posts?tags=13401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}