{"id":15020,"count":1,"description":"","link":"https:\/\/blogs.bmj.com\/bmjopen\/tag\/aids\/","name":"aids","slug":"aids","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>aids Archives - BMJ Open<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bmj.com\/bmjopen\/tag\/aids\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"aids Archives - BMJ Open\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bmj.com\/bmjopen\/tag\/aids\/\" \/>\n<meta property=\"og:site_name\" content=\"BMJ Open\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/tag\\\/aids\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/tag\\\/aids\\\/\",\"name\":\"aids Archives - BMJ Open\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/tag\\\/aids\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/tag\\\/aids\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"aids\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/\",\"name\":\"BMJ Open\",\"description\":\"The official blog BMJ Open; a place to discuss medical research and discover the Editor&#039;s monthly top picks.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/#organization\",\"name\":\"BMJ Open\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/files\\\/2017\\\/10\\\/blog-logo-bmjopen.png\",\"contentUrl\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/files\\\/2017\\\/10\\\/blog-logo-bmjopen.png\",\"width\":183,\"height\":34,\"caption\":\"BMJ Open\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjopen\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"aids Archives - BMJ Open","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bmj.com\/bmjopen\/tag\/aids\/","og_locale":"en_US","og_type":"article","og_title":"aids Archives - BMJ Open","og_url":"https:\/\/blogs.bmj.com\/bmjopen\/tag\/aids\/","og_site_name":"BMJ Open","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.bmj.com\/bmjopen\/tag\/aids\/","url":"https:\/\/blogs.bmj.com\/bmjopen\/tag\/aids\/","name":"aids Archives - BMJ Open","isPartOf":{"@id":"https:\/\/blogs.bmj.com\/bmjopen\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.bmj.com\/bmjopen\/tag\/aids\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bmj.com\/bmjopen\/tag\/aids\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bmj.com\/bmjopen\/"},{"@type":"ListItem","position":2,"name":"aids"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bmj.com\/bmjopen\/#website","url":"https:\/\/blogs.bmj.com\/bmjopen\/","name":"BMJ Open","description":"The official blog BMJ Open; a place to discuss medical research and discover the Editor&#039;s monthly top picks.","publisher":{"@id":"https:\/\/blogs.bmj.com\/bmjopen\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bmj.com\/bmjopen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blogs.bmj.com\/bmjopen\/#organization","name":"BMJ Open","url":"https:\/\/blogs.bmj.com\/bmjopen\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bmj.com\/bmjopen\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.bmj.com\/bmjopen\/files\/2017\/10\/blog-logo-bmjopen.png","contentUrl":"https:\/\/blogs.bmj.com\/bmjopen\/files\/2017\/10\/blog-logo-bmjopen.png","width":183,"height":34,"caption":"BMJ Open"},"image":{"@id":"https:\/\/blogs.bmj.com\/bmjopen\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.bmj.com\/bmjopen\/wp-json\/wp\/v2\/tags\/15020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bmj.com\/bmjopen\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.bmj.com\/bmjopen\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.bmj.com\/bmjopen\/wp-json\/wp\/v2\/posts?tags=15020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}