{"id":343,"count":1,"description":"","link":"https:\/\/blogs.bmj.com\/bmjgh\/category\/polio\/","name":"Polio","slug":"polio","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Polio Archives - BMJ Global Health blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bmj.com\/bmjgh\/category\/polio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polio Archives - BMJ Global Health blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bmj.com\/bmjgh\/category\/polio\/\" \/>\n<meta property=\"og:site_name\" content=\"BMJ Global Health blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/category\\\/polio\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/category\\\/polio\\\/\",\"name\":\"Polio Archives - BMJ Global Health blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/category\\\/polio\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/category\\\/polio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/\",\"name\":\"BMJ Global Health blog\",\"description\":\"Comment, discussion and debate on all aspects of global health across BMJ\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/#organization\",\"name\":\"BMJ Global Health blog\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/files\\\/2017\\\/11\\\/blog-logo-gh.png\",\"contentUrl\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/files\\\/2017\\\/11\\\/blog-logo-gh.png\",\"width\":275,\"height\":34,\"caption\":\"BMJ Global Health blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjgh\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Polio Archives - BMJ Global Health blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bmj.com\/bmjgh\/category\/polio\/","og_locale":"en_US","og_type":"article","og_title":"Polio Archives - BMJ Global Health blog","og_url":"https:\/\/blogs.bmj.com\/bmjgh\/category\/polio\/","og_site_name":"BMJ Global Health blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.bmj.com\/bmjgh\/category\/polio\/","url":"https:\/\/blogs.bmj.com\/bmjgh\/category\/polio\/","name":"Polio Archives - BMJ Global Health blog","isPartOf":{"@id":"https:\/\/blogs.bmj.com\/bmjgh\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.bmj.com\/bmjgh\/category\/polio\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bmj.com\/bmjgh\/category\/polio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bmj.com\/bmjgh\/"},{"@type":"ListItem","position":2,"name":"Polio"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bmj.com\/bmjgh\/#website","url":"https:\/\/blogs.bmj.com\/bmjgh\/","name":"BMJ Global Health blog","description":"Comment, discussion and debate on all aspects of global health across BMJ","publisher":{"@id":"https:\/\/blogs.bmj.com\/bmjgh\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bmj.com\/bmjgh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blogs.bmj.com\/bmjgh\/#organization","name":"BMJ Global Health blog","url":"https:\/\/blogs.bmj.com\/bmjgh\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bmj.com\/bmjgh\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.bmj.com\/bmjgh\/files\/2017\/11\/blog-logo-gh.png","contentUrl":"https:\/\/blogs.bmj.com\/bmjgh\/files\/2017\/11\/blog-logo-gh.png","width":275,"height":34,"caption":"BMJ Global Health blog"},"image":{"@id":"https:\/\/blogs.bmj.com\/bmjgh\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.bmj.com\/bmjgh\/wp-json\/wp\/v2\/categories\/343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bmj.com\/bmjgh\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.bmj.com\/bmjgh\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.bmj.com\/bmjgh\/wp-json\/wp\/v2\/posts?categories=343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}