{"id":14367,"count":1,"description":"","link":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/category\/respiratory_pulmonary\/","name":"Respiratory \/ Pulmonary","slug":"respiratory_pulmonary","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Respiratory \/ Pulmonary Archives - BMJ EBM Spotlight<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bmj.com\/bmjebmspotlight\/category\/respiratory_pulmonary\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Respiratory \/ Pulmonary Archives - BMJ EBM Spotlight\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bmj.com\/bmjebmspotlight\/category\/respiratory_pulmonary\/\" \/>\n<meta property=\"og:site_name\" content=\"BMJ EBM Spotlight\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/category\\\/respiratory_pulmonary\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/category\\\/respiratory_pulmonary\\\/\",\"name\":\"Respiratory \\\/ Pulmonary Archives - BMJ EBM Spotlight\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/category\\\/respiratory_pulmonary\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/category\\\/respiratory_pulmonary\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Respiratory \\\/ Pulmonary\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/\",\"name\":\"BMJ EBM Spotlight\",\"description\":\"The new blog for the journal BMJ Evidence-Based Medicine, edited by Carl Heneghan\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/#organization\",\"name\":\"BMJ EBM Spotlight\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/files\\\/2017\\\/10\\\/admin-ajax.png\",\"contentUrl\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/files\\\/2017\\\/10\\\/admin-ajax.png\",\"width\":300,\"height\":34,\"caption\":\"BMJ EBM Spotlight\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmjebmspotlight\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Respiratory \/ Pulmonary Archives - BMJ EBM Spotlight","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/category\/respiratory_pulmonary\/","og_locale":"en_GB","og_type":"article","og_title":"Respiratory \/ Pulmonary Archives - BMJ EBM Spotlight","og_url":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/category\/respiratory_pulmonary\/","og_site_name":"BMJ EBM Spotlight","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/category\/respiratory_pulmonary\/","url":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/category\/respiratory_pulmonary\/","name":"Respiratory \/ Pulmonary Archives - BMJ EBM Spotlight","isPartOf":{"@id":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/category\/respiratory_pulmonary\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/category\/respiratory_pulmonary\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/"},{"@type":"ListItem","position":2,"name":"Respiratory \/ Pulmonary"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/#website","url":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/","name":"BMJ EBM Spotlight","description":"The new blog for the journal BMJ Evidence-Based Medicine, edited by Carl Heneghan","publisher":{"@id":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/#organization","name":"BMJ EBM Spotlight","url":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/files\/2017\/10\/admin-ajax.png","contentUrl":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/files\/2017\/10\/admin-ajax.png","width":300,"height":34,"caption":"BMJ EBM Spotlight"},"image":{"@id":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/wp-json\/wp\/v2\/categories\/14367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.bmj.com\/bmjebmspotlight\/wp-json\/wp\/v2\/posts?categories=14367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}