{"id":1305,"count":1,"description":"","link":"https:\/\/blogs.bmj.com\/bmj\/tag\/virgin-atlantic\/","name":"Virgin Atlantic","slug":"virgin-atlantic","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Virgin Atlantic Archives - The BMJ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bmj.com\/bmj\/tag\/virgin-atlantic\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Virgin Atlantic Archives - The BMJ\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bmj.com\/bmj\/tag\/virgin-atlantic\/\" \/>\n<meta property=\"og:site_name\" content=\"The BMJ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bmj_latest\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/tag\\\/virgin-atlantic\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/tag\\\/virgin-atlantic\\\/\",\"name\":\"Virgin Atlantic Archives - The BMJ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/tag\\\/virgin-atlantic\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/tag\\\/virgin-atlantic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Virgin Atlantic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/\",\"name\":\"The BMJ\",\"description\":\"Helping doctors make better decisions.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/#organization\",\"name\":\"The BMJ\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/files\\\/2018\\\/05\\\/The-BMJ-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/files\\\/2018\\\/05\\\/The-BMJ-logo.jpg\",\"width\":852,\"height\":568,\"caption\":\"The BMJ\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/bmj\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bmjdotcom\\\/\",\"https:\\\/\\\/x.com\\\/bmj_latest\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Virgin Atlantic Archives - The BMJ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bmj.com\/bmj\/tag\/virgin-atlantic\/","og_locale":"en_US","og_type":"article","og_title":"Virgin Atlantic Archives - The BMJ","og_url":"https:\/\/blogs.bmj.com\/bmj\/tag\/virgin-atlantic\/","og_site_name":"The BMJ","twitter_card":"summary_large_image","twitter_site":"@bmj_latest","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.bmj.com\/bmj\/tag\/virgin-atlantic\/","url":"https:\/\/blogs.bmj.com\/bmj\/tag\/virgin-atlantic\/","name":"Virgin Atlantic Archives - The BMJ","isPartOf":{"@id":"https:\/\/blogs.bmj.com\/bmj\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.bmj.com\/bmj\/tag\/virgin-atlantic\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bmj.com\/bmj\/tag\/virgin-atlantic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bmj.com\/bmj\/"},{"@type":"ListItem","position":2,"name":"Virgin Atlantic"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bmj.com\/bmj\/#website","url":"https:\/\/blogs.bmj.com\/bmj\/","name":"The BMJ","description":"Helping doctors make better decisions.","publisher":{"@id":"https:\/\/blogs.bmj.com\/bmj\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bmj.com\/bmj\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blogs.bmj.com\/bmj\/#organization","name":"The BMJ","url":"https:\/\/blogs.bmj.com\/bmj\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bmj.com\/bmj\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.bmj.com\/bmj\/files\/2018\/05\/The-BMJ-logo.jpg","contentUrl":"https:\/\/blogs.bmj.com\/bmj\/files\/2018\/05\/The-BMJ-logo.jpg","width":852,"height":568,"caption":"The BMJ"},"image":{"@id":"https:\/\/blogs.bmj.com\/bmj\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bmjdotcom\/","https:\/\/x.com\/bmj_latest"]}]}},"_links":{"self":[{"href":"https:\/\/blogs.bmj.com\/bmj\/wp-json\/wp\/v2\/tags\/1305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bmj.com\/bmj\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.bmj.com\/bmj\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.bmj.com\/bmj\/wp-json\/wp\/v2\/posts?tags=1305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}