{"id":296,"count":2,"description":"","link":"https:\/\/blogs.bmj.com\/adc\/category\/archimedes\/cf\/","name":"CF","slug":"cf","taxonomy":"category","parent":79,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CF Archives - ADC Online Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bmj.com\/adc\/category\/archimedes\/cf\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CF Archives - ADC Online Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bmj.com\/adc\/category\/archimedes\/cf\/\" \/>\n<meta property=\"og:site_name\" content=\"ADC Online Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/category\\\/archimedes\\\/cf\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/category\\\/archimedes\\\/cf\\\/\",\"name\":\"CF Archives - ADC Online Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/category\\\/archimedes\\\/cf\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/category\\\/archimedes\\\/cf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"archimedes\",\"item\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/category\\\/archimedes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/\",\"name\":\"ADC Online Blog\",\"description\":\"Education, debate, and meandering thoughts on child health, using evidence and research.\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/#organization\",\"name\":\"ADC Online Blog\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/files\\\/2017\\\/10\\\/blog-logo-adc.png\",\"contentUrl\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/files\\\/2017\\\/10\\\/blog-logo-adc.png\",\"width\":285,\"height\":34,\"caption\":\"ADC Online Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bmj.com\\\/adc\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CF Archives - ADC Online Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bmj.com\/adc\/category\/archimedes\/cf\/","og_locale":"en_GB","og_type":"article","og_title":"CF Archives - ADC Online Blog","og_url":"https:\/\/blogs.bmj.com\/adc\/category\/archimedes\/cf\/","og_site_name":"ADC Online Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogs.bmj.com\/adc\/category\/archimedes\/cf\/","url":"https:\/\/blogs.bmj.com\/adc\/category\/archimedes\/cf\/","name":"CF Archives - ADC Online Blog","isPartOf":{"@id":"https:\/\/blogs.bmj.com\/adc\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.bmj.com\/adc\/category\/archimedes\/cf\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bmj.com\/adc\/category\/archimedes\/cf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bmj.com\/adc\/"},{"@type":"ListItem","position":2,"name":"archimedes","item":"https:\/\/blogs.bmj.com\/adc\/category\/archimedes\/"},{"@type":"ListItem","position":3,"name":"CF"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bmj.com\/adc\/#website","url":"https:\/\/blogs.bmj.com\/adc\/","name":"ADC Online Blog","description":"Education, debate, and meandering thoughts on child health, using evidence and research.","publisher":{"@id":"https:\/\/blogs.bmj.com\/adc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bmj.com\/adc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/blogs.bmj.com\/adc\/#organization","name":"ADC Online Blog","url":"https:\/\/blogs.bmj.com\/adc\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/blogs.bmj.com\/adc\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.bmj.com\/adc\/files\/2017\/10\/blog-logo-adc.png","contentUrl":"https:\/\/blogs.bmj.com\/adc\/files\/2017\/10\/blog-logo-adc.png","width":285,"height":34,"caption":"ADC Online Blog"},"image":{"@id":"https:\/\/blogs.bmj.com\/adc\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.bmj.com\/adc\/wp-json\/wp\/v2\/categories\/296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bmj.com\/adc\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.bmj.com\/adc\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blogs.bmj.com\/adc\/wp-json\/wp\/v2\/categories\/79"}],"wp:post_type":[{"href":"https:\/\/blogs.bmj.com\/adc\/wp-json\/wp\/v2\/posts?categories=296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}